{"id":543,"count":6,"description":"","link":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/","name":"Baghdad","slug":"baghdad","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/\" \/>\n<meta property=\"og:site_name\" content=\"Shahennews Eng\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/archives\\\/tag\\\/baghdad\\\/\",\"url\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/archives\\\/tag\\\/baghdad\\\/\",\"name\":\"Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/archives\\\/tag\\\/baghdad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/archives\\\/tag\\\/baghdad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baghdad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/\",\"name\":\"Shahennews Eng\",\"description\":\"Shahennews.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#organization\",\"name\":\"Shahennews Eng\",\"url\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/log-1.jpg\",\"contentUrl\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/log-1.jpg\",\"width\":200,\"height\":214,\"caption\":\"Shahennews Eng\"},\"image\":{\"@id\":\"https:\\\/\\\/shahennews.com\\\/eng\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/","og_locale":"en_US","og_type":"article","og_title":"Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng","og_url":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/","og_site_name":"Shahennews Eng","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/","url":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/","name":"Baghdad \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - Shahennews Eng","isPartOf":{"@id":"https:\/\/shahennews.com\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/shahennews.com\/eng\/archives\/tag\/baghdad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/shahennews.com\/eng\/"},{"@type":"ListItem","position":2,"name":"Baghdad"}]},{"@type":"WebSite","@id":"https:\/\/shahennews.com\/eng\/#website","url":"https:\/\/shahennews.com\/eng\/","name":"Shahennews Eng","description":"Shahennews.com","publisher":{"@id":"https:\/\/shahennews.com\/eng\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shahennews.com\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shahennews.com\/eng\/#organization","name":"Shahennews Eng","url":"https:\/\/shahennews.com\/eng\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shahennews.com\/eng\/#\/schema\/logo\/image\/","url":"https:\/\/shahennews.com\/eng\/wp-content\/uploads\/2021\/07\/log-1.jpg","contentUrl":"https:\/\/shahennews.com\/eng\/wp-content\/uploads\/2021\/07\/log-1.jpg","width":200,"height":214,"caption":"Shahennews Eng"},"image":{"@id":"https:\/\/shahennews.com\/eng\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shahennews.com\/eng\/wp-json\/wp\/v2\/tags\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shahennews.com\/eng\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/shahennews.com\/eng\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/shahennews.com\/eng\/wp-json\/wp\/v2\/posts?tags=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}